{"id":16296,"date":"2012-05-26T10:38:27","date_gmt":"2012-05-26T08:38:27","guid":{"rendered":"https:\/\/mamchenkov.net\/wordpress\/?p=16296"},"modified":"2012-05-26T10:38:27","modified_gmt":"2012-05-26T08:38:27","slug":"los-colorados-du-hast-official-rammstein-cover","status":"publish","type":"post","link":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/","title":{"rendered":"Los Colorados &#8211; Du Hast (Official Rammstein Cover)"},"content":{"rendered":"<!-- google_ad_section_start -->\n<p>I&#8217;ve seen plenty covers on Rammstein&#8217;s &#8220;Du Hast&#8221;, but I think this one is one of the best ever.<\/p>\n<p style=\"text-align: center;\"><div class=\"jetpack-video-wrapper\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"660\" height=\"372\" src=\"https:\/\/www.youtube.com\/embed\/a5xSxGhlHfc?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-US&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/div><\/p>\n<p>&nbsp;<\/p>\n<!-- google_ad_section_end -->\n","protected":false},"excerpt":{"rendered":"<!-- google_ad_section_start -->\n<p>I&#8217;ve seen plenty covers on Rammstein&#8217;s &#8220;Du Hast&#8221;, but I think this one is one of the best ever. &nbsp;<\/p>\n<!-- google_ad_section_end -->\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[1,31],"tags":[3004,1299,1908],"keyring_services":[],"class_list":["post-16296","post","type-post","status-publish","format-standard","hentry","category-general","category-music","tag-los-colorados","tag-rammstein","tag-youtube-videos"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"I&#039;ve seen plenty covers on Rammstein&#039;s &quot;Du Hast&quot;, but I think this one is one of the best ever.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Leonid Mamchenkov\"\/>\n\t<meta name=\"google-site-verification\" content=\"VHvdD0_usx1_4DzKy_QCVcICVgX2EgA2ybELT-wl7kQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Leonid Mamchenkov - Life, universe, and everything else\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Colorados \u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov\" \/>\n\t\t<meta property=\"og:description\" content=\"I&#039;ve seen plenty covers on Rammstein&#039;s &quot;Du Hast&quot;, but I think this one is one of the best ever.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mamchenkov.net\/wordpress\/wp-content\/uploads\/2026\/03\/leonid-sailing-beer.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mamchenkov.net\/wordpress\/wp-content\/uploads\/2026\/03\/leonid-sailing-beer.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-05-26T08:38:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-05-26T08:38:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MamchenkovBlog\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@mamchenkov\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Colorados \u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov\" \/>\n\t\t<meta name=\"twitter:description\" content=\"I&#039;ve seen plenty covers on Rammstein&#039;s &quot;Du Hast&quot;, but I think this one is one of the best ever.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@mamchenkov\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mamchenkov.net\/wordpress\/wp-content\/uploads\/2026\/03\/leonid-sailing-beer.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#blogposting\",\"name\":\"Los Colorados \\u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov\",\"headline\":\"Los Colorados &#8211; Du Hast (Official Rammstein Cover)\",\"author\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/author\\\/leonid\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#articleImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cf6df002a284d78fb6e9d8222ca4d102e0832035ed6bc8447008bd234e131a4?s=96&d=identicon&r=g\",\"width\":96,\"height\":96,\"caption\":\"Leonid Mamchenkov\"},\"datePublished\":\"2012-05-26T10:38:27+02:00\",\"dateModified\":\"2012-05-26T10:38:27+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#webpage\"},\"articleSection\":\"All, Music, Los Colorados, Rammstein, YouTube videos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/category\\\/general\\\/#listItem\",\"name\":\"All\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/category\\\/general\\\/#listItem\",\"position\":2,\"name\":\"All\",\"item\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/category\\\/general\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#listItem\",\"name\":\"Los Colorados &#8211; Du Hast (Official Rammstein Cover)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#listItem\",\"position\":3,\"name\":\"Los Colorados &#8211; Du Hast (Official Rammstein Cover)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/category\\\/general\\\/#listItem\",\"name\":\"All\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/#person\",\"name\":\"Leonid Mamchenkov\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cf6df002a284d78fb6e9d8222ca4d102e0832035ed6bc8447008bd234e131a4?s=96&d=identicon&r=g\",\"width\":96,\"height\":96,\"caption\":\"Leonid Mamchenkov\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/author\\\/leonid\\\/#author\",\"url\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/author\\\/leonid\\\/\",\"name\":\"Leonid Mamchenkov\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3cf6df002a284d78fb6e9d8222ca4d102e0832035ed6bc8447008bd234e131a4?s=96&d=identicon&r=g\",\"width\":96,\"height\":96,\"caption\":\"Leonid Mamchenkov\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#webpage\",\"url\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/\",\"name\":\"Los Colorados \\u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov\",\"description\":\"I've seen plenty covers on Rammstein's \\\"Du Hast\\\", but I think this one is one of the best ever.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/2012\\\/05\\\/26\\\/los-colorados-du-hast-official-rammstein-cover\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/author\\\/leonid\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/author\\\/leonid\\\/#author\"},\"datePublished\":\"2012-05-26T10:38:27+02:00\",\"dateModified\":\"2012-05-26T10:38:27+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/\",\"name\":\"Blog of Leonid Mamchenkov\",\"description\":\"Life, universe, and everything else\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/mamchenkov.net\\\/wordpress\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Colorados \u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov","description":"I've seen plenty covers on Rammstein's \"Du Hast\", but I think this one is one of the best ever.","canonical_url":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"VHvdD0_usx1_4DzKy_QCVcICVgX2EgA2ybELT-wl7kQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#blogposting","name":"Los Colorados \u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov","headline":"Los Colorados &#8211; Du Hast (Official Rammstein Cover)","author":{"@id":"https:\/\/mamchenkov.net\/wordpress\/author\/leonid\/#author"},"publisher":{"@id":"https:\/\/mamchenkov.net\/wordpress\/#person"},"image":{"@type":"ImageObject","@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#articleImage","url":"https:\/\/secure.gravatar.com\/avatar\/3cf6df002a284d78fb6e9d8222ca4d102e0832035ed6bc8447008bd234e131a4?s=96&d=identicon&r=g","width":96,"height":96,"caption":"Leonid Mamchenkov"},"datePublished":"2012-05-26T10:38:27+02:00","dateModified":"2012-05-26T10:38:27+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#webpage"},"isPartOf":{"@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#webpage"},"articleSection":"All, Music, Los Colorados, Rammstein, YouTube videos"},{"@type":"BreadcrumbList","@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mamchenkov.net\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/mamchenkov.net\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/#listItem","name":"All"}},{"@type":"ListItem","@id":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/#listItem","position":2,"name":"All","item":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#listItem","name":"Los Colorados &#8211; Du Hast (Official Rammstein Cover)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mamchenkov.net\/wordpress#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#listItem","position":3,"name":"Los Colorados &#8211; Du Hast (Official Rammstein Cover)","previousItem":{"@type":"ListItem","@id":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/#listItem","name":"All"}}]},{"@type":"Person","@id":"https:\/\/mamchenkov.net\/wordpress\/#person","name":"Leonid Mamchenkov","image":{"@type":"ImageObject","@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/3cf6df002a284d78fb6e9d8222ca4d102e0832035ed6bc8447008bd234e131a4?s=96&d=identicon&r=g","width":96,"height":96,"caption":"Leonid Mamchenkov"}},{"@type":"Person","@id":"https:\/\/mamchenkov.net\/wordpress\/author\/leonid\/#author","url":"https:\/\/mamchenkov.net\/wordpress\/author\/leonid\/","name":"Leonid Mamchenkov","image":{"@type":"ImageObject","@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3cf6df002a284d78fb6e9d8222ca4d102e0832035ed6bc8447008bd234e131a4?s=96&d=identicon&r=g","width":96,"height":96,"caption":"Leonid Mamchenkov"}},{"@type":"WebPage","@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#webpage","url":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/","name":"Los Colorados \u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov","description":"I've seen plenty covers on Rammstein's \"Du Hast\", but I think this one is one of the best ever.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/mamchenkov.net\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/#breadcrumblist"},"author":{"@id":"https:\/\/mamchenkov.net\/wordpress\/author\/leonid\/#author"},"creator":{"@id":"https:\/\/mamchenkov.net\/wordpress\/author\/leonid\/#author"},"datePublished":"2012-05-26T10:38:27+02:00","dateModified":"2012-05-26T10:38:27+02:00"},{"@type":"WebSite","@id":"https:\/\/mamchenkov.net\/wordpress\/#website","url":"https:\/\/mamchenkov.net\/wordpress\/","name":"Blog of Leonid Mamchenkov","description":"Life, universe, and everything else","inLanguage":"en-US","publisher":{"@id":"https:\/\/mamchenkov.net\/wordpress\/#person"}}]},"og:locale":"en_US","og:site_name":"Leonid Mamchenkov - Life, universe, and everything else","og:type":"article","og:title":"Los Colorados \u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov","og:description":"I've seen plenty covers on Rammstein's &quot;Du Hast&quot;, but I think this one is one of the best ever.","og:url":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/","og:image":"https:\/\/mamchenkov.net\/wordpress\/wp-content\/uploads\/2026\/03\/leonid-sailing-beer.jpg","og:image:secure_url":"https:\/\/mamchenkov.net\/wordpress\/wp-content\/uploads\/2026\/03\/leonid-sailing-beer.jpg","og:image:width":1024,"og:image:height":1024,"article:published_time":"2012-05-26T08:38:27+00:00","article:modified_time":"2012-05-26T08:38:27+00:00","article:publisher":"https:\/\/www.facebook.com\/MamchenkovBlog","twitter:card":"summary_large_image","twitter:site":"@mamchenkov","twitter:title":"Los Colorados \u2013 Du Hast (Official Rammstein Cover) - Leonid Mamchenkov","twitter:description":"I've seen plenty covers on Rammstein's &quot;Du Hast&quot;, but I think this one is one of the best ever.","twitter:creator":"@mamchenkov","twitter:image":"https:\/\/mamchenkov.net\/wordpress\/wp-content\/uploads\/2026\/03\/leonid-sailing-beer.jpg"},"aioseo_meta_data":{"post_id":"16296","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-07-20 00:09:37","updated":"2026-01-15 07:51:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mamchenkov.net\/wordpress\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mamchenkov.net\/wordpress\/category\/general\/\" title=\"All\">All<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Colorados \u2013 Du Hast (Official Rammstein Cover)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mamchenkov.net\/wordpress"},{"label":"All","link":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/"},{"label":"Los Colorados &#8211; Du Hast (Official Rammstein Cover)","link":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/26\/los-colorados-du-hast-official-rammstein-cover\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":19051,"url":"https:\/\/mamchenkov.net\/wordpress\/2013\/12\/26\/du-hast-sandsturm\/","url_meta":{"origin":16296,"position":0},"title":"Du hast Sandsturm","author":"Leonid Mamchenkov","date":"December 26, 2013","format":false,"excerpt":"I think this is the most disturbing Rammstein remix I've ever heard. \u00a0It's both horrible and amazing at the same time. \u00a0It shouldn't exist, yet I can't stop listening to it. \u00a0What's wrong with me??? https:\/\/soundcloud.com\/mixessss25\/rammstein-vs-darude-vaski Oh, and yes, I've discovered SoundCloud.com yesterday.","rel":"","context":"In &quot;All&quot;","block_context":{"text":"All","link":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11942,"url":"https:\/\/mamchenkov.net\/wordpress\/2009\/11\/25\/day-in-brief\/","url_meta":{"origin":16296,"position":1},"title":"Day in brief","author":"Leonid Mamchenkov","date":"November 25, 2009","format":false,"excerpt":"I favorited a YouTube video -- Flyleaf - I'm So Sick MUSIC VIDEO http:\/\/www.youtube.com\/watch?v.....re_twitter # I favorited a YouTube video -- Rammstein-Amerika http:\/\/www.youtube.com\/watch?v.....re_twitter # I favorited a YouTube video -- Bullet For My Valentine - Tears Don't Fall http:\/\/bit.ly\/Irnpr #","rel":"","context":"In &quot;All&quot;","block_context":{"text":"All","link":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27988,"url":"https:\/\/mamchenkov.net\/wordpress\/2017\/09\/12\/do-class\/","url_meta":{"origin":16296,"position":2},"title":"do class","author":"Leonid Mamchenkov","date":"September 12, 2017","format":false,"excerpt":"This one is for all the geeky Rammstein fans :)","rel":"","context":"In &quot;All&quot;","block_context":{"text":"All","link":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mamchenkov.net\/wordpress\/wp-content\/uploads\/2017\/09\/do-class-500x500.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11004,"url":"https:\/\/mamchenkov.net\/wordpress\/2008\/01\/04\/elvis-beatles-nirvana-then-who\/","url_meta":{"origin":16296,"position":3},"title":"Elvis, Beatles, Nirvana, then who?","author":"Leonid Mamchenkov","date":"January 4, 2008","format":false,"excerpt":"Matthew Sidney Long brings up an interesting point with a challange: Please name me a band over the past 10 years who has come close to Nirvana in sheer impact and talent since Kurt put shotgun to mouth above garage in 1994? (and, I'm not talking about some indie band\u2026","rel":"","context":"In &quot;All&quot;","block_context":{"text":"All","link":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16302,"url":"https:\/\/mamchenkov.net\/wordpress\/2012\/05\/27\/weekly-digest-2012-05-27\/","url_meta":{"origin":16296,"position":4},"title":"Weekly digest &#8211; 2012-05-27","author":"Leonid Mamchenkov","date":"May 27, 2012","format":false,"excerpt":"Krombacher #beer http:\/\/t.co\/QLx8r7QZ # Beer color http:\/\/t.co\/EpLDXtZR # Hungarian porn star with the surname Angel, actually makes me wanna go to heaven. #EveAngel http:\/\/t.co\/g0dOn3Xf # Krombacher #beer http:\/\/t.co\/92ron8x9 # Ketchup #kelvin #food http:\/\/t.co\/dXUym2LG # Pork chop #sutro #food http:\/\/t.co\/9uTuldo5 # New note : \u0428\u0442\u0440\u0430\u0444\u044b \u0437\u0430 \u043d\u0435\u0441\u0430\u043d\u043a\u0446\u0438\u043e\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0435 \u043c\u0438\u0442\u0438\u043d\u0433\u0438 \u0432 \u043d\u0435\u043a\u043e\u0442\u043e\u0440\u044b\u0445 \u0441\u0442\u0440\u0430\u043d\u0430\u0445\u2026","rel":"","context":"In &quot;All&quot;","block_context":{"text":"All","link":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":15895,"url":"https:\/\/mamchenkov.net\/wordpress\/2011\/11\/12\/day-in-brief-2011-11-12\/","url_meta":{"origin":16296,"position":5},"title":"Day in brief &#8211; 2011-11-12","author":"Leonid Mamchenkov","date":"November 12, 2011","format":false,"excerpt":"@savvides @RottenTomatoes I thinl it was long and boring. No story. No nudity. Awesome fights, but too few and far apart. # Rammstein - Mein Land on Vimeo http:\/\/t.co\/RnRFYllH # I'm at MyMall http:\/\/t.co\/ocBzMz5J # @savvides Good idea :-) #","rel":"","context":"In &quot;All&quot;","block_context":{"text":"All","link":"https:\/\/mamchenkov.net\/wordpress\/category\/general\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/posts\/16296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/comments?post=16296"}],"version-history":[{"count":0,"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/posts\/16296\/revisions"}],"wp:attachment":[{"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/media?parent=16296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/categories?post=16296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/tags?post=16296"},{"taxonomy":"keyring_services","embeddable":true,"href":"https:\/\/mamchenkov.net\/wordpress\/wp-json\/wp\/v2\/keyring_services?post=16296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}